{"id":15434,"date":"2025-02-26T14:15:20","date_gmt":"2025-02-26T13:15:20","guid":{"rendered":"https:\/\/nalanda-monastery.eu\/?page_id=15434"},"modified":"2025-09-20T14:44:59","modified_gmt":"2025-09-20T12:44:59","slug":"losar-2025","status":"publish","type":"page","link":"https:\/\/nalanda-monastery.eu\/fr\/losar-2025\/","title":{"rendered":"Losar 02\/25"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"15434\" class=\"elementor elementor-15434\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa65291 elementor-section-height-min-height elementor-section-full_width elementor-section-height-default elementor-section-items-middle\" data-id=\"aa65291\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;opacity-fan&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 283.5 19.6\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.33\" d=\"M0 0L0 18.8 141.8 4.1 283.5 18.8 283.5 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.33\" d=\"M0 0L0 12.6 141.8 4 283.5 12.6 283.5 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.33\" d=\"M0 0L0 6.4 141.8 4 283.5 6.4 283.5 0z\"\/>\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L0 1.2 141.8 4 283.5 1.2 283.5 0z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5a3402c\" data-id=\"5a3402c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f38dcde elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f38dcde\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\">LOSAR 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-340ede4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"340ede4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-medium\">C\u00e9l\u00e9bration du nouvel an tib\u00e9tain<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6824f98 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6824f98\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\">Ven, 28 Feb 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bb3428 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bb3428\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f146a2\" data-id=\"4f146a2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f45fdfb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f45fdfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vendredi 28 f\u00e9vrier 2025<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-location-arrow\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Le monast\u00e8re Nalanda<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e82ea5d elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e82ea5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,0.9,11.1,6.9,11.1S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c29d6db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c29d6db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-39e0876\" data-id=\"39e0876\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-366aee8 elementor-widget elementor-widget-image\" data-id=\"366aee8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"737\" height=\"1024\" src=\"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-737x1024.jpg\" class=\"attachment-large size-large wp-image-15444\" alt=\"Une repr\u00e9sentation du champ de m\u00e9rites\" srcset=\"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-737x1024.jpg 737w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-216x300.jpg 216w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-768x1068.jpg 768w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-1105x1536.jpg 1105w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-1473x2048.jpg 1473w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-9x12.jpg 9w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-800x1112.jpg 800w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-scaled.jpg 1842w\" sizes=\"(max-width: 737px) 100vw, 737px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0d5895 elementor-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"a0d5895\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjEyMzQiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Faire un don<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91de3e3 elementor-widget elementor-widget-text-editor\" data-id=\"91de3e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>Veuillez choisir \u00ab Give where most needed \u00bb (donner l\u00e0 o\u00f9 c'est le plus n\u00e9cessaire) dans le menu d\u00e9roulant et sp\u00e9cifier la destination et les noms pour une d\u00e9dicace sp\u00e9ciale.<br \/><\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a212204 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a212204\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl translation-block\">En direct : <b>Lama Ch\u00f6pa &amp; Tsog<\/b><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae776f8 elementor-widget elementor-widget-video\" data-id=\"ae776f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=r24adp_obAs&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-5a35cde\" data-id=\"5a35cde\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a12985b elementor-widget elementor-widget-text-editor\" data-id=\"a12985b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><b>Le Losar occupe une place particuli\u00e8re dans nos c\u0153urs car nous nous souvenons de l'anniversaire du parinirvana du fondateur de la FPMT et du monast\u00e8re de Nalanda, Lama Y\u00e9sh\u00e9. En l'honneur de cette occasion, Lama Zopa Rinpoch\u00e9 a encourag\u00e9 les centres \u00e0 offrir aux \u00e9tudiants l'opportunit\u00e9 de s'engager dans une pouja de Lama Ch\u00f6pa avec tsog. Nous organiserons la pouja \u00e0 19 heures et <a href=\"https:\/\/www.youtube.com\/watch?v=r24adp_obAs\">elle sera diffus\u00e9e en direct sur notre cha\u00eene YouTube<\/a> pour celles et ceux qui souhaitent se joindre \u00e0 nous virtuellement.<\/b><\/div><div>\u00a0<\/div><div><div class=\" translation-block\">Il convient de mentionner que le Losar et les quinze jours qui suivent sont consid\u00e9r\u00e9s comme particuli\u00e8rement propices, car ils sont cens\u00e9s multiplier les m\u00e9rites. Selon le texte du Vinaya \u00ab Tr\u00e9sor des citations et de la logique \u00bb, le m\u00e9rite des actions vertueuses accomplies pendant cette p\u00e9riode peut \u00eatre multipli\u00e9 par 100 millions. Rejoignez-nous pour <a href=\"\u00ab\" target=\"\u00ab\">le deuxi\u00e8me Monlam gu\u00e9loug<\/a> qui d\u00e9butera le 11 mars 2025 pour 5 jours !<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8296f2a elementor-widget elementor-widget-accordion\" data-id=\"8296f2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1361\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1361\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Programme<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1361\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1361\"><p><strong>12:30 : D\u00e9jeuner de Losar<\/strong><\/p><p class=\" translation-block\">Veuillez <a href=\"\u00ab\" target=\"\u00ab\">vous inscrire en utilisant ce lien.<\/a><\/p><p><strong>19h:00 : Gourou Pouja<\/strong><\/p><p class=\" translation-block\">N'h\u00e9sitez pas \u00e0 nous rejoindre sur place dans la gompa principale, ou <a href=\"\u00ab\" target=\"\u00ab\">en ligne en utilisant ce lien.<\/a><\/p><p><strong>Offrandes de lumi\u00e8re<\/strong><\/p><p class=\" translation-block\">Afin d'accumuler de nombreux m\u00e9rites en ce jour tr\u00e8s sp\u00e9cial, vous pouvez <a href=\"\u00ab\" target=\"\u00ab\">offrir des lampes \u00e0 led tib\u00e9taines<\/a> (10\u20ac chacune) pour vous-m\u00eame ou vos proches. Votre nom sera mentionn\u00e9 pour chaque lampe que vous offrirez.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1362\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1362\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Soutien &amp; D\u00e9dicaces<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1362\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1362\"><div><p>\u00a0<\/p><p>Si vous souhaitez soutenir les offrandes pour notre gourou pouja (Lama Ch\u00f6pa &amp; tsog), veuillez cliquer sur le bouton \u00ab Donate \u00bb \u00e0 gauche et s\u00e9lectionner \u00ab Give where most needed \u00bb (donner l\u00e0 o\u00f9 c'est le plus n\u00e9cessaire) dans le menu d\u00e9roulant. Vous aurez alors la possibilit\u00e9 d'indiquer o\u00f9 diriger ce don, ainsi que toute d\u00e9dicace sp\u00e9ciale.<\/p><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05cc779 elementor-widget elementor-widget-image\" data-id=\"05cc779\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-1024x768.jpg\" class=\"attachment-large size-large wp-image-15451\" alt=\"\" srcset=\"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-1024x768.jpg 1024w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-300x225.jpg 300w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-768x576.jpg 768w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-1536x1152.jpg 1536w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-2048x1536.jpg 2048w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-16x12.jpg 16w, https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lampes-800x600.jpg 800w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>LOSAR 2025 Tibetan New Year Celebration Fri, 28 Feb 2025 Friday, 28 February 2025 Nalanda Monastery Donate Please choose &#8220;Give where most needed&#8221; in the dropdown menu &amp; specify the destination and names for special dedication. Live: Lama Chopa &amp; Tsog https:\/\/www.youtube.com\/watch?v=r24adp_obAsLosar holds a special place in our hearts as we remember the anniversary of &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/nalanda-monastery.eu\/fr\/losar-2025\/\"> <span class=\"screen-reader-text\">Losar 02\/25<\/span> Lire la suite\u00a0\u00bb<\/a><\/p>","protected":false},"author":121,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"give_campaign_id":0,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-15434","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Celebrating Losar, Tibetan New Year - Nalanda Monastery<\/title>\n<meta name=\"description\" content=\"For us, Losar is a special time as it commemorates the anniversary of FPMT\u2019s &amp; Nalanda Monastery\u2019s founder Lama Yeshe\u2019s parinirvana at dawn of Losar in 1984. Lama Zopa Rinpoche asks centers to offer students the opportunity to offer extensive Lama Chopa with tsog in honor of this anniversary, which we will do 7 PM. The puja would be live-streamed on our YouTube channel for those interested to join us online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nalanda-monastery.eu\/fr\/losar-2025\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrating Losar, Tibetan New Year - Nalanda Monastery\" \/>\n<meta property=\"og:description\" content=\"For us, Losar is a special time as it commemorates the anniversary of FPMT\u2019s &amp; Nalanda Monastery\u2019s founder Lama Yeshe\u2019s parinirvana at dawn of Losar in 1984. Lama Zopa Rinpoche asks centers to offer students the opportunity to offer extensive Lama Chopa with tsog in honor of this anniversary, which we will do 7 PM. The puja would be live-streamed on our YouTube channel for those interested to join us online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nalanda-monastery.eu\/fr\/losar-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Nalanda Monastery\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Nalanda.Monastery\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-20T12:44:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1842\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/\",\"url\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/\",\"name\":\"Celebrating Losar, Tibetan New Year - Nalanda Monastery\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nalanda-monastery.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/lamachopa-737x1024.jpg\",\"datePublished\":\"2025-02-26T13:15:20+00:00\",\"dateModified\":\"2025-09-20T12:44:59+00:00\",\"description\":\"For us, Losar is a special time as it commemorates the anniversary of FPMT\u2019s & Nalanda Monastery\u2019s founder Lama Yeshe\u2019s parinirvana at dawn of Losar in 1984. Lama Zopa Rinpoche asks centers to offer students the opportunity to offer extensive Lama Chopa with tsog in honor of this anniversary, which we will do 7 PM. The puja would be live-streamed on our YouTube channel for those interested to join us online.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nalanda-monastery.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/lamachopa-737x1024.jpg\",\"contentUrl\":\"https:\\\/\\\/nalanda-monastery.eu\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/lamachopa-737x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/losar-2025\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nalanda-monastery.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Losar 02\\\/25\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/#website\",\"url\":\"https:\\\/\\\/nalanda-monastery.eu\\\/\",\"name\":\"Nalanda Monastery\",\"description\":\"Tibetan buddhist monastery in the Gelugpa tradition; Dharma studies and practice\",\"publisher\":{\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nalanda-monastery.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/#organization\",\"name\":\"Nalanda Monastery\",\"url\":\"https:\\\/\\\/nalanda-monastery.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/nalanda-monastery.eu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Spiritual-Logo-nntransparent-72dpi-white-4-copy.png\",\"contentUrl\":\"https:\\\/\\\/nalanda-monastery.eu\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Spiritual-Logo-nntransparent-72dpi-white-4-copy.png\",\"width\":400,\"height\":438,\"caption\":\"Nalanda Monastery\"},\"image\":{\"@id\":\"https:\\\/\\\/nalanda-monastery.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Nalanda.Monastery\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9l\u00e9bration du Losar, le nouvel an tib\u00e9tain - Monast\u00e8re de Nalanda","description":"Pour nous, le Losar est un moment sp\u00e9cial car il comm\u00e9more l'anniversaire du fondateur de la FPMT et du monast\u00e8re de Nalanda, Lama Yeshe, qui a atteint le parinirvana \u00e0 l'aube du Losar en 1984. Lama Zopa Rinpoch\u00e9 demande aux centres d'offrir aux \u00e9tudiants la possibilit\u00e9 d'offrir un Lama Chopa \u00e9tendu avec tsog en l'honneur de cet anniversaire, ce que nous ferons \u00e0 19 heures. La puja sera retransmise en direct sur notre cha\u00eene YouTube pour les personnes int\u00e9ress\u00e9es \u00e0 se joindre \u00e0 nous en ligne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nalanda-monastery.eu\/fr\/losar-2025\/","og_locale":"fr_FR","og_type":"article","og_title":"Celebrating Losar, Tibetan New Year - Nalanda Monastery","og_description":"For us, Losar is a special time as it commemorates the anniversary of FPMT\u2019s & Nalanda Monastery\u2019s founder Lama Yeshe\u2019s parinirvana at dawn of Losar in 1984. Lama Zopa Rinpoche asks centers to offer students the opportunity to offer extensive Lama Chopa with tsog in honor of this anniversary, which we will do 7 PM. The puja would be live-streamed on our YouTube channel for those interested to join us online.","og_url":"https:\/\/nalanda-monastery.eu\/fr\/losar-2025\/","og_site_name":"Nalanda Monastery","article_publisher":"https:\/\/www.facebook.com\/Nalanda.Monastery\/","article_modified_time":"2025-09-20T12:44:59+00:00","og_image":[{"width":1842,"height":2560,"url":"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nalanda-monastery.eu\/losar-2025\/","url":"https:\/\/nalanda-monastery.eu\/losar-2025\/","name":"C\u00e9l\u00e9bration du Losar, le nouvel an tib\u00e9tain - Monast\u00e8re de Nalanda","isPartOf":{"@id":"https:\/\/nalanda-monastery.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nalanda-monastery.eu\/losar-2025\/#primaryimage"},"image":{"@id":"https:\/\/nalanda-monastery.eu\/losar-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-737x1024.jpg","datePublished":"2025-02-26T13:15:20+00:00","dateModified":"2025-09-20T12:44:59+00:00","description":"Pour nous, le Losar est un moment sp\u00e9cial car il comm\u00e9more l'anniversaire du fondateur de la FPMT et du monast\u00e8re de Nalanda, Lama Yeshe, qui a atteint le parinirvana \u00e0 l'aube du Losar en 1984. Lama Zopa Rinpoch\u00e9 demande aux centres d'offrir aux \u00e9tudiants la possibilit\u00e9 d'offrir un Lama Chopa \u00e9tendu avec tsog en l'honneur de cet anniversaire, ce que nous ferons \u00e0 19 heures. La puja sera retransmise en direct sur notre cha\u00eene YouTube pour les personnes int\u00e9ress\u00e9es \u00e0 se joindre \u00e0 nous en ligne.","breadcrumb":{"@id":"https:\/\/nalanda-monastery.eu\/losar-2025\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nalanda-monastery.eu\/losar-2025\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nalanda-monastery.eu\/losar-2025\/#primaryimage","url":"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-737x1024.jpg","contentUrl":"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2025\/02\/lamachopa-737x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nalanda-monastery.eu\/losar-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nalanda-monastery.eu\/"},{"@type":"ListItem","position":2,"name":"Losar 02\/25"}]},{"@type":"WebSite","@id":"https:\/\/nalanda-monastery.eu\/#website","url":"https:\/\/nalanda-monastery.eu\/","name":"Le monast\u00e8re Nalanda","description":"Tibetan buddhist monastery in the Gelugpa tradition; Dharma studies and practice","publisher":{"@id":"https:\/\/nalanda-monastery.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nalanda-monastery.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/nalanda-monastery.eu\/#organization","name":"Le monast\u00e8re Nalanda","url":"https:\/\/nalanda-monastery.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/nalanda-monastery.eu\/#\/schema\/logo\/image\/","url":"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2020\/04\/Spiritual-Logo-nntransparent-72dpi-white-4-copy.png","contentUrl":"https:\/\/nalanda-monastery.eu\/wp-content\/uploads\/2020\/04\/Spiritual-Logo-nntransparent-72dpi-white-4-copy.png","width":400,"height":438,"caption":"Nalanda Monastery"},"image":{"@id":"https:\/\/nalanda-monastery.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Nalanda.Monastery\/"]}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/pages\/15434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/users\/121"}],"replies":[{"embeddable":true,"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/comments?post=15434"}],"version-history":[{"count":23,"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/pages\/15434\/revisions"}],"predecessor-version":[{"id":17601,"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/pages\/15434\/revisions\/17601"}],"wp:attachment":[{"href":"https:\/\/nalanda-monastery.eu\/fr\/wp-json\/wp\/v2\/media?parent=15434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}